{"id":8686,"date":"2021-01-21T17:22:44","date_gmt":"2021-01-21T16:22:44","guid":{"rendered":"https:\/\/www.lowi.es\/blog\/?p=8686"},"modified":"2022-11-21T16:15:41","modified_gmt":"2022-11-21T15:15:41","slug":"buscar-en-instagram-personas-telefonos-publicaciones","status":"publish","type":"post","link":"https:\/\/www.lowi.es\/blog\/buscar-en-instagram-personas-telefonos-publicaciones\/","title":{"rendered":"C\u00f3mo buscar en Instagram personas, tel\u00e9fonos o contenido"},"content":{"rendered":"<p><b>Instagram es la aplicaci\u00f3n favorita para el cotilleo<\/b><span style=\"font-weight: 400;\"> mundial. No pasa nada, adm\u00edtelo, todos queremos saber de la vida de los dem\u00e1s y, salvo que sea una obsesi\u00f3n, no es malo. Es m\u00e1s, en ocasiones incluso nos metemos a ver la vida de ciertos famosos que, en circunstancias normales, nos dar\u00eda verg\u00fcenza reconocer. Si tu labio se ha arqueado con una sonrisa c\u00f3mplice, <\/span><b>te recomiendo que borres el historial de b\u00fasquedas de tu cuenta de Instagram<\/b><span style=\"font-weight: 400;\">. No queremos que alguien pueda verla y te juzgue por ello.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de para jugar a las viejas del visillo, Instagram sirve para otras muchas cosas. Es un <\/span><b>gran escaparate al mundo para marcas<\/b><span style=\"font-weight: 400;\"> y emprendedores que han visto en esta red social una de las <\/span><b>v\u00edas principales de captaci\u00f3n de clientes<\/b><span style=\"font-weight: 400;\">. De hecho, desde que Instagram naci\u00f3 hasta ahora ha cambiado bastante. Ya no es algo pensado solo para fot\u00f3grafos ni se trata de un \u00e1lbum est\u00e1tico de im\u00e1genes. <strong>Instagram es actividad pura y dura<\/strong>: comentarios, stories que cambian cada segundo, reels (<\/span><a href=\"https:\/\/www.lowi.es\/blog\/que-es-instagram-reels-como-se-usa-y-como-hacer-un-reels\/\"><span style=\"font-weight: 400;\">te contamos lo que son<\/span><\/a><span style=\"font-weight: 400;\">, si todav\u00eda no lo sabes) e interacci\u00f3n constante.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As\u00ed que, seas del grupo que seas: vieja del visillo o emprendedor en busca de clientes, es importante que conozcas <\/span><b>c\u00f3mo se busca en Instagram<\/b><span style=\"font-weight: 400;\"> y qu\u00e9 informaci\u00f3n puedes encontrar a trav\u00e9s del buscador de la aplicaci\u00f3n.\u00a0<\/span><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79_2 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #696969;color:#696969\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #696969;color:#696969\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.lowi.es\/blog\/buscar-en-instagram-personas-telefonos-publicaciones\/#Como_y_que_podemos_buscar_en_Instagram\" >C\u00f3mo y qu\u00e9 podemos buscar en Instagram\u00a0<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.lowi.es\/blog\/buscar-en-instagram-personas-telefonos-publicaciones\/#%C2%BFComo_buscar_personas_en_Instagram\" >\u00bfC\u00f3mo buscar personas en Instagram?\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.lowi.es\/blog\/buscar-en-instagram-personas-telefonos-publicaciones\/#%C2%BFSe_puede_buscar_por_numero_de_telefono\" >\u00bfSe puede buscar por n\u00famero de tel\u00e9fono?\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.lowi.es\/blog\/buscar-en-instagram-personas-telefonos-publicaciones\/#%C2%BFPodemos_buscar_palabras_clave_en_Instagram\" >\u00bfPodemos buscar palabras clave en Instagram?\u00a0<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Como_y_que_podemos_buscar_en_Instagram\"><\/span><b>C\u00f3mo y qu\u00e9 podemos buscar en Instagram\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFComo_buscar_personas_en_Instagram\"><\/span><b>\u00bfC\u00f3mo buscar personas en Instagram?\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La principal b\u00fasqueda en Instagram es por nombre de cuenta<span style=\"font-weight: 400;\">, que en muchos casos son nombres de personas. <\/span><span style=\"font-weight: 400;\">Instagram te ir\u00e1 mostrando cuentas que coinciden con las letras que vas escribiendo en su buscador, como hace Google. Lo que te facilitar\u00e1 bastante la vida a la hora de encontrar a la persona o marca en cuesti\u00f3n.\u00a0<\/span><\/p>\n<p><b>\u00bfC\u00f3mo puedes afinar la b\u00fasqueda de personas?<\/b><span style=\"font-weight: 400;\"> Si no has puesto la @ al hacer tu b\u00fasqueda (por ejemplo @manoloeldelbombo), es posible que se te est\u00e9n colando en los resultados no solo personas sino tambi\u00e9n hashtags y lugares. En este caso, para hacer una b\u00fasqueda m\u00e1s exacta, <strong>lo ideal es que tengas seleccionado el icono de la personita<\/strong>, como se muestra en la imagen de abajo. Lo mismo si lo que quieres es buscar por hashtag o lugares.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8689 size-large\" src=\"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-personas-en-instagram-594x1000.jpg\" alt=\"C\u00f3mo buscar personas en Instagram\" width=\"594\" height=\"1000\" srcset=\"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-personas-en-instagram-594x1000.jpg 594w, https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-personas-en-instagram-178x300.jpg 178w, https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-personas-en-instagram-768x1294.jpg 768w, https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-personas-en-instagram-912x1536.jpg 912w, https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-personas-en-instagram.jpg 1080w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFSe_puede_buscar_por_numero_de_telefono\"><\/span><b>\u00bfSe puede buscar por n\u00famero de tel\u00e9fono?\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">S\u00ed y no. Es decir, <\/span><b>no podr\u00e1s encontrar a alguien por su n\u00famero de tel\u00e9fono<\/b><span style=\"font-weight: 400;\"> si previamente no es un contacto de tu agenda. El buscador de Instagram no est\u00e1 pensado para que podamos introducir en \u00e9l un n\u00famero de tel\u00e9fono y nos aparezca como por arte de magia el perfil de una persona o de un local.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, s\u00ed <\/span><b>podemos saber si nuestros contactos de Facebook o de la agenda telef\u00f3nica est\u00e1n en Instagram<\/b><span style=\"font-weight: 400;\">. \u00bfC\u00f3mo?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Solo tendr\u00e1s que darle a la opci\u00f3n del men\u00fa: <\/span><b>Descubrir personas<\/b><span style=\"font-weight: 400;\"> y dar los permisos pertinentes para conectar con los datos de tu agenda.\u00a0<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFPodemos_buscar_palabras_clave_en_Instagram\"><\/span><b>\u00bfPodemos buscar palabras clave en Instagram?\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">S\u00ed, y esto <\/span><b>si eres una marca o emprendedor te pondr\u00e1 muy contento<\/b><span style=\"font-weight: 400;\">. Aunque tenemos una mala noticia y es que, como la mayor\u00eda de las cosas, se ha empezado probando en pa\u00edses de habla inglesa y <\/span><b>no sabemos cu\u00e1ndo ni de qu\u00e9 manera llegar\u00e1 a Espa\u00f1a<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si finalmente Instagram acaba implementando esta funcionalidad en nuestro pa\u00eds podr\u00eda ser una gran herramienta para que el contenido de cuentas p\u00fablicas aparezca con mayor facilidad como <strong>resultado de b\u00fasquedas de usuarios<\/strong>.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Parece que Instagram sigue avanzando. Ya sabes que les gusta lanzar actualizaciones cada poco tiempo, ya sea en temas de dise\u00f1o o de nuevas funcionalidades. La app de Instagram ofrece m\u00e1s que un simple visionado de fotos o la interacci\u00f3n a trav\u00e9s de stories. <\/span><b>\u00bfUtilizas sus colecciones y destacados?<\/b><span style=\"font-weight: 400;\"> \u00bfHas creado listas de tus mejores amigos? Son cosas muy \u00fatiles que te est\u00e1n esperando. As\u00ed que, mientras llegan la b\u00fasqueda por palabras clave, \u00bfpor qu\u00e9 no pruebas el resto de opciones?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a1Por cierto! Si quieres que tus fotos tengan un mont\u00f3n de likes, haz magia con estos <\/span><a href=\"https:\/\/www.lowi.es\/blog\/accesorios-hacer-fotos-con-movil\/\"><span style=\"font-weight: 400;\">7 accesorios para el m\u00f3vil<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 podemos buscar en Instagram? Descubre c\u00f3mo buscar personas, tel\u00e9fonos o t\u00e9rminos en esta red social de manera s\u00faper sencilla. Y t\u00fa, \u00bfqu\u00e9 quieres encontrar en Instagram?<\/p>\n","protected":false},"author":5,"featured_media":8688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[7],"tags":[197,221],"class_list":["post-8686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guias","tag-como-se-hace","tag-redes-sociales"],"jetpack_featured_media_url":"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg","uagb_featured_image_src":{"full":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",751,400,false],"thumbnail":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram-150x150.jpg",150,150,true],"medium":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram-300x160.jpg",300,160,true],"medium_large":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",751,400,false],"large":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",751,400,false],"1536x1536":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",751,400,false],"2048x2048":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",751,400,false],"authorship-box-avatar":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",150,80,false],"authorship-box-related":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",70,37,false],"small":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",300,160,false],"yarpp-thumbnail":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2021\/01\/buscar-en-instagram.jpg",120,64,false]},"uagb_author_info":{"display_name":"Lowi","author_link":"https:\/\/www.lowi.es\/blog\/autor\/blog-lowi\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00bfQu\u00e9 podemos buscar en Instagram? Descubre c\u00f3mo buscar personas, tel\u00e9fonos o t\u00e9rminos en esta red social de manera s\u00faper sencilla. Y t\u00fa, \u00bfqu\u00e9 quieres encontrar en Instagram?","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/8686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/comments?post=8686"}],"version-history":[{"count":2,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/8686\/revisions"}],"predecessor-version":[{"id":8690,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/8686\/revisions\/8690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/media\/8688"}],"wp:attachment":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/media?parent=8686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/categories?post=8686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/tags?post=8686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}