{"id":8447,"date":"2020-11-13T11:00:51","date_gmt":"2020-11-13T10:00:51","guid":{"rendered":"https:\/\/www.lowi.es\/blog\/?p=8447"},"modified":"2022-05-03T09:14:53","modified_gmt":"2022-05-03T07:14:53","slug":"app-radarcovid","status":"publish","type":"post","link":"https:\/\/www.lowi.es\/blog\/app-radarcovid\/","title":{"rendered":"App RadarCOVID: Qu\u00e9 es y como funciona"},"content":{"rendered":"<p>El 2020 ha sido un a\u00f1o raro y duro para todos. Por eso, en Lowi queremos mejorarlo y necesitamos tu ayuda para hacerlo.<br \/>\n\u00bfC\u00f3mo? Descargando la app oficial del Gobierno de Espa\u00f1a, RadarCOVID. Con ella, evitaremos que el virus se extienda m\u00e1s de la cuenta. Cuantas m\u00e1s personas tengamos la app descargada, m\u00e1s preparados estaremos para prevenir el Coronavirus.<\/p>\n<h2>\u00bfQu\u00e9 hace esta app?<\/h2>\n<p>Pues avisarte del contacto que has tenido en los \u00faltimos d\u00edas con alguien diagnosticado de COVID-19. <strong>Funciona a trav\u00e9s de un \u201crastreo autom\u00e1tico\u201d que permite localizar esa cadena de contactos<\/strong> y as\u00ed operar mucho m\u00e1s r\u00e1pido.<\/p>\n<p>Pero hoy en d\u00eda, en el mundo de webs, apps, e internet en general, hay un tema que nos preocupa mucho\u2026 nuestra privacidad. Por esa parte puedes estar tranquilo, El <strong>RadarCOVID no te identifica, por lo que nunca sabr\u00e1 qui\u00e9n eres ni con qui\u00e9n has estado<\/strong>. Tampoco recoge datos de ubicaci\u00f3n as\u00ed que no sabr\u00e1 d\u00f3nde te encuentras.<\/p>\n<p>Y ahora viene la gran pregunta\u2026 \u00bfC\u00f3mo funciona?<br \/>\nAtento, que te lo explicamos brevemente\u2026<\/p>\n<h2>\u00bfC\u00f3mo funciona RadarCOVID?<\/h2>\n<p>Sales de casa un d\u00eda para ir al trabajo o hacer la compra. Llevas encima tu m\u00f3vil con la <strong>app instalada y activa<\/strong> y te encuentras con un conocido que tambi\u00e9n lleva RadarCOVID activada en su bolsillo. Hace mucho que no os v\u00e9is y os qued\u00e1is hablando de la vida 15 minutos. Y a menos de 2 metros de distancia. En ese momento, vuestros tel\u00e9fonos emiten una se\u00f1al de Bluetooth con un c\u00f3digo aleatorio y cada m\u00f3vil recordar\u00e1 el c\u00f3digo identificador del otro. An\u00f3nimos siempre, por supuesto.<\/p>\n<p>Pasados unos d\u00edas, empiezas a tener s\u00edntomas y vas al Centro de Salud. All\u00ed te hacen una PCR y resulta que es positiva. <strong>El personal sanitario te dar\u00e1 un c\u00f3digo de diagn\u00f3stico<\/strong> (an\u00f3nimo s\u00ed) para que de forma voluntaria lo introduzcas en la app. Cuando lo hagas, se enviar\u00e1 una notificaci\u00f3n a todos los terminales que tengan tu identificador memorizado, es decir, a todos los que estuvieron en contacto cercano contigo.<\/p>\n<p>Y ahora que ya tienes el funcionamiento interiorizado, solo te queda seguir estos pasos:<\/p>\n<ol>\n<li>Descarga la app RadarCovid<\/li>\n<li>Da permiso a bluetooth y sus notificaciones<\/li>\n<li>D\u00e9jala siempre activa<\/li>\n<\/ol>\n<p>Gracias a ti, los dem\u00e1s podr\u00e1n tomar precauciones para proteger al resto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 2020 ha sido un a\u00f1o raro y duro para todos. Por eso, en Lowi queremos mejorarlo y necesitamos tu ayuda para hacerlo.<br \/>\n\u00bfC\u00f3mo? Descargando la app oficial del Gobierno de Espa\u00f1a, RadarCOVID. Con ella, evitaremos que el virus se extienda m\u00e1s de la cuenta. Cuantas m\u00e1s personas tengamos la app descargada, m\u00e1s preparados estaremos para prevenir el Coronavirus.<\/p>\n","protected":false},"author":5,"featured_media":8453,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[6],"tags":[207],"class_list":["post-8447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-tendencias"],"uagb_featured_image_src":{"full":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",600,400,false],"thumbnail":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid-150x150.jpg",150,150,true],"medium":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",600,400,false],"large":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",600,400,false],"1536x1536":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",600,400,false],"2048x2048":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",600,400,false],"authorship-box-avatar":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",150,100,false],"authorship-box-related":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",70,47,false],"small":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",300,200,false],"yarpp-thumbnail":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg",120,80,false]},"uagb_author_info":{"display_name":"Lowi","author_link":"https:\/\/www.lowi.es\/blog\/autor\/blog-lowi\/"},"uagb_comment_info":2,"uagb_excerpt":"El 2020 ha sido un a\u00f1o raro y duro para todos. Por eso, en Lowi queremos mejorarlo y necesitamos tu ayuda para hacerlo. \u00bfC\u00f3mo? Descargando la app oficial del Gobierno de Espa\u00f1a, RadarCOVID. Con ella, evitaremos que el virus se extienda m\u00e1s de la cuenta. Cuantas m\u00e1s personas tengamos la app descargada, m\u00e1s preparados estaremos&hellip;","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2020\/11\/App-Radarcovid.jpg","_links":{"self":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/8447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/comments?post=8447"}],"version-history":[{"count":4,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/8447\/revisions"}],"predecessor-version":[{"id":8455,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/8447\/revisions\/8455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/media\/8453"}],"wp:attachment":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/media?parent=8447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/categories?post=8447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/tags?post=8447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}