{"id":5027,"date":"2018-05-17T09:00:11","date_gmt":"2018-05-17T07:00:11","guid":{"rendered":"https:\/\/www.lowi.es\/blog\/?p=5027"},"modified":"2022-10-25T14:34:49","modified_gmt":"2022-10-25T12:34:49","slug":"todo-lo-que-necesitas-saber-sobre-android-wear-os","status":"publish","type":"post","link":"https:\/\/www.lowi.es\/blog\/todo-lo-que-necesitas-saber-sobre-android-wear-os\/","title":{"rendered":"Todo lo que necesitas saber sobre Android Wear OS"},"content":{"rendered":"<p>Wear OS es el sistema operativo de Google, basado en Android y dise\u00f1ado para relojes inteligentes y otros dispositivos <em>wearables<\/em>.<\/p>\n<p>Hasta hace poco, Wear OS era conocido como Android Wear, pero desde su versi\u00f3n 2.10 (presentada por Google en marzo de 2018) adopta ese nombre oficial de Wear OS.<\/p>\n<p>Hoy te contamos todo lo que necesitas saber sobre Wear OS, qu\u00e9 puede hacer y qu\u00e9 puedes esperar de \u00e9l en el futuro.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79_2 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #696969;color:#696969\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #696969;color:#696969\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.lowi.es\/blog\/todo-lo-que-necesitas-saber-sobre-android-wear-os\/#Que_puedes_hacer_con_un_dispositivo_con_Wear_OS\" >Qu\u00e9 puedes hacer con un dispositivo con Wear OS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.lowi.es\/blog\/todo-lo-que-necesitas-saber-sobre-android-wear-os\/#Que_dispositivos_son_compatibles_con_Wear_OS\" >Qu\u00e9 dispositivos son compatibles con Wear OS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.lowi.es\/blog\/todo-lo-que-necesitas-saber-sobre-android-wear-os\/#El_futuro_de_Wear_OS\" >El futuro de Wear OS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.lowi.es\/blog\/todo-lo-que-necesitas-saber-sobre-android-wear-os\/#%C2%BFPuedes_usar_Wear_OS_con_tu_iPhone\" >\u00bfPuedes usar Wear OS con tu iPhone?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Que_puedes_hacer_con_un_dispositivo_con_Wear_OS\"><\/span>Qu\u00e9 puedes hacer con un dispositivo con Wear OS<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Los relojes y dispositivos inteligentes se han transformado en los \u00faltimos a\u00f1os para tener \u00e9xito. Al principio, se ofrec\u00edan como un complemento del m\u00f3vil y, para algunas cosas, un sustituto.<\/p>\n<p>Pero su poca usabilidad en cosas importantes no convenc\u00eda mucho. As\u00ed que se han reposicionado, sobre todo, <strong>como instrumento deportivo y para la salud<\/strong>. Puedes salir a correr con tu reloj dejando el m\u00f3vil en casa, monitorizar tu sue\u00f1o, tus latidos\u2026<\/p>\n<p>Hay que tener en cuenta que <strong>Wear OS tiene el Asistente de Google integrado<\/strong>. Eso permite manejar el <em>wearable<\/em> mediante voz, y realizar casi todas las tareas que puedes hacer con el asistente en tu m\u00f3vil.<\/p>\n<p>Algunas de las principales caracter\u00edsticas de Wear OS, en su \u00faltima versi\u00f3n, son:<\/p>\n<ul>\n<li><strong>Encontrar una ubicaci\u00f3n<\/strong> y el tiempo de viaje a trav\u00e9s de aplicaci\u00f3n de mapas. Tambi\u00e9n conocer el tiempo de llegada y recibir indicaciones, mediante vibraciones, de giros y cambios de direcci\u00f3n.<\/li>\n<li><strong>Gestionar tu calendario<\/strong> de Google, tareas y recordatorios.<\/li>\n<li>Recibir <strong>informaci\u00f3n del tiempo<\/strong>.<\/li>\n<li><strong>Encontrar respuestas<\/strong> a preguntas.<\/li>\n<li>Manejar tu <strong>m\u00fasica<\/strong>.<\/li>\n<li>A trav\u00e9s de la app <em>Google Fit<\/em> podremos monitorizar nuestros pasos, ritmo card\u00edaco, sue\u00f1o\u2026 Y consultarlo mediante voz con el Asistente de Google.<\/li>\n<li>Recibir <strong>notificaciones<\/strong> de llamadas, mensajes, Whatsapp&#8230;<\/li>\n<\/ul>\n<p>Y muchas cosas m\u00e1s.<\/p>\n<p>Hay que tener en cuenta, por supuesto, que Wear OS puede realizar ciertas cosas solo <strong>si el dispositivo tiene esa capacidad<\/strong>.<\/p>\n<p>Es decir, si nuestro reloj o pulsera no tienen un sensor para ritmo card\u00edaco, o no pueden registrar ciertas actividades, como nadar, esas funciones de Wear OS no estar\u00e1n accesibles.<\/p>\n<p>Lo mismo pasa con la aplicaci\u00f3n de mapas, por ejemplo, si el dispositivo no las puede instalar, no las tendr\u00e1s.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Que_dispositivos_son_compatibles_con_Wear_OS\"><\/span><span lang=\"es\">Qu\u00e9 dispositivos son compatibles con Wear OS<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5029\" src=\"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/wear-os.jpg\" alt=\"Wear OS\" width=\"750\" height=\"387\" srcset=\"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/wear-os.jpg 750w, https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/wear-os-300x155.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Pr\u00e1cticamente todos los smartwatches de las grandes marcas, excepto Apple, que tiene su sistema propio Watch OS, y Samsung, que tambi\u00e9n tiene su sistema propio, Tizen OS.<\/p>\n<p>Empresas como Asus, Huawei, LG, etc, usan Wear OS en sus relojes. Otras marcas de lujo, como Louis Vuitton o Montblanc, tambi\u00e9n lo usan en sus l\u00edneas de <em>smartwatches<\/em>.<\/p>\n<p>Wear OS permite la personalizaci\u00f3n del sistema, con lo que algunos fabricantes hacen sus propias modificaciones est\u00e9ticas.<\/p>\n<p>Cuando vayas a comprar tu <em>smartwatch<\/em>, inf\u00f3rmate bien de qu\u00e9 sistema operativo lleva, porque muchos relojes chinos baratos no llevan Wear OS aunque lo parezca.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"El_futuro_de_Wear_OS\"><\/span>El futuro de Wear OS<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Como vemos, gracias al deporte y la salud, los <em>smartwatches<\/em> han encontrado su hueco, as\u00ed que Wear OS tiene futuro.<\/p>\n<p>Google ya ha dicho que se centrar\u00e1 en <strong>potenciar el aspecto de la salud<\/strong>, con un seguimiento m\u00e1s profundo, <em>coaching<\/em> para que seamos m\u00e1s activos y nuevas prestaciones.<\/p>\n<p>Adem\u00e1s, tambi\u00e9n quieren mejorar mucho el Asistente de Google, para que lo uses de manera habitual, en vez de tocar la pantalla de tu reloj.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFPuedes_usar_Wear_OS_con_tu_iPhone\"><\/span>\u00bfPuedes usar Wear OS con tu iPhone?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La respuesta es <strong>s\u00ed<\/strong>.<\/p>\n<p>Los relojes y pulseras inteligentes funcionan combinados con tu tel\u00e9fono. El m\u00f3vil guarda datos, sincroniza, se comunica para notificaciones y llamadas\u2026<\/p>\n<p>As\u00ed que, si tienes un iPhone, no es necesario que te cambies a un m\u00f3vil Android. <strong>Puedes comprarte un smartwatch que tenga Wear OS y manejarlo desde tu tel\u00e9fono Apple<\/strong>.<\/p>\n<p>Para ello, puedes descargar Wear OS para iOS gratis <a href=\"https:\/\/itunes.apple.com\/es\/app\/wear-os-by-google-smartwatch\/id986496028?mt=8\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a>.<\/p>\n<p>As\u00ed que ya lo ves, no hay excusa, los <em>smartwatches<\/em> han venido para quedarse. Y Wear OS es cada vez m\u00e1s \u00fatil y poderoso, sobre todo gracias a que tienes al Asistente de Google en tu mu\u00f1eca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wear OS es el sistema operativo de Google, basado en Android y dise\u00f1ado para relojes inteligentes y otros dispositivos wearables. Te contamos qu\u00e9 puedes hacer con un dispositivo con Wear OS, qu\u00e9 dispositivos son compatibles y cu\u00e1les son sus expectativas de futuro.<\/p>\n","protected":false},"author":5,"featured_media":10444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[6],"tags":[205],"class_list":["post-5027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-novedades"],"jetpack_featured_media_url":"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg","uagb_featured_image_src":{"full":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",750,400,false],"thumbnail":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1-150x150.jpeg",150,150,true],"medium":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1-300x160.jpeg",300,160,true],"medium_large":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",750,400,false],"large":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",750,400,false],"1536x1536":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",750,400,false],"2048x2048":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",750,400,false],"authorship-box-avatar":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",150,80,false],"authorship-box-related":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",70,37,false],"small":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",300,160,false],"yarpp-thumbnail":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2018\/05\/Blog_22-1-1.jpeg",120,64,false]},"uagb_author_info":{"display_name":"Lowi","author_link":"https:\/\/www.lowi.es\/blog\/autor\/blog-lowi\/"},"uagb_comment_info":0,"uagb_excerpt":"Wear OS es el sistema operativo de Google, basado en Android y dise\u00f1ado para relojes inteligentes y otros dispositivos wearables. Te contamos qu\u00e9 puedes hacer con un dispositivo con Wear OS, qu\u00e9 dispositivos son compatibles y cu\u00e1les son sus expectativas de futuro.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/5027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/comments?post=5027"}],"version-history":[{"count":2,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/5027\/revisions"}],"predecessor-version":[{"id":8092,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/5027\/revisions\/8092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/media\/10444"}],"wp:attachment":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/media?parent=5027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/categories?post=5027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/tags?post=5027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}