{"id":1614,"date":"2016-07-13T10:42:26","date_gmt":"2016-07-13T08:42:26","guid":{"rendered":"https:\/\/www.lowi.es\/blog\/?p=1614"},"modified":"2022-10-21T13:07:08","modified_gmt":"2022-10-21T11:07:08","slug":"descubre-como-estan-triunfando-los-moviles-indios","status":"publish","type":"post","link":"https:\/\/www.lowi.es\/blog\/descubre-como-estan-triunfando-los-moviles-indios\/","title":{"rendered":"Descubre c\u00f3mo est\u00e1n triunfando los m\u00f3viles indios"},"content":{"rendered":"<p>Primero llegaron los m\u00f3viles chinos pisando fuerte en el mercado espa\u00f1ol con marcas como Xioami, Huawei o Meizu. \u00a1Ahora es el turno de los m\u00f3viles indios! Las empresas de telefon\u00eda india est\u00e1n ganando relevancia y presencia poco a poco<\/p>\n<p>Es el caso de Intex, que quiere introducir sus tel\u00e9fonos en Espa\u00f1a a partir del pr\u00f3ximo 1 de septiembre. Todos sus <em>smartphones<\/em> llevan el sistema operativo de Android y \u00a1con 4 a\u00f1os de garant\u00eda!&#8230;Algo que pocas empresas de telefon\u00eda ofrecen a d\u00eda de hoy.<\/p>\n<p>Nosotros queremos presentarte 2 de los 3 tel\u00e9fonos que Intex quiere poner a la venta el pr\u00f3ximo 1 de septiembre en Espa\u00f1a.<\/p>\n<h2><strong>Intex Aqua S9 Pro\u00a0\u00a0\u00a0\u00a0 <\/strong><\/h2>\n<p>Este <em>smartphone<\/em> viene con un procesador MediaTek de 4 n\u00facleos a 1,3 GHz y 2 GB de RAM. Su memoria es de 16 GB ampliables hasta 128 GB con una tarjeta microSD y el sistema operativo es Android Marshmallow.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1616 aligncenter\" src=\"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/Aqua-S9-Pro.jpg\" alt=\"Aqua S9 Pro\" width=\"600\" height=\"485\" \/><\/p>\n<p>Por otro lado, las c\u00e1maras tienen 13 <em>megap\u00edxeles<\/em> en la trasera y 5 <em>megap\u00edxeles<\/em> en la frontal y adem\u00e1s el m\u00f3vil incluye dualSIM, algo muy c\u00f3modo si tienes tel\u00e9fono de empresa.<\/p>\n<p>La pantalla es de 5,5 pulgadas, perfecta para ver fotos o v\u00eddeos y la bater\u00eda est\u00e1 bastante bien porque es de 3.670 mAh y atenci\u00f3n \u00a1extra\u00edble! Adem\u00e1s, lo guay es que te viene con una funda y un protector de pantalla incluidos en la caja, lo que esta superbi\u00e9n.<\/p>\n<p>El precio es de tan solo \u00a1185 euros!<\/p>\n<h2><strong>Intex Aqua Shine 4G<\/strong><\/h2>\n<p>El procesador de este m\u00f3vil es un MediaTek de 4 n\u00facleos a 1 GHz y 2 GB de RAM. Tiene un almacenamiento de 16 GB ampliables hasta 128 GB con una tarjeta microSD.<\/p>\n<p>Las c\u00e1maras son un poco inferiores que las del modelo anterior (Aqua S9 Pro) con 8 <em>megap\u00edxeles<\/em> en la parte trasera y 5 <em>megap\u00edxeles<\/em> en la frontal. Baja un poco la calidad de la c\u00e1mara, que eso para el d\u00eda a d\u00eda se nota.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1617 aligncenter\" src=\"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/Aqua-Shine-4G.jpg\" alt=\"Aqua Shine 4G\" width=\"601\" height=\"511\" srcset=\"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/Aqua-Shine-4G.jpg 630w, https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/Aqua-Shine-4G-300x255.jpg 300w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/p>\n<p>Tambi\u00e9n posee el sistema dualSIM y la pantalla es de 5 pulgadas, la est\u00e1ndar de la mayor\u00eda de los <em>smartphones<\/em> de ahora. El sistema operativo es Android Lollipop, anterior al Marshmallow que lleva el Aqua S9 Pro.<\/p>\n<p>Tambi\u00e9n incluye funda y protector de pantalla en la caja y su bater\u00eda no est\u00e1 nada mal, es de 3000 mAh.<\/p>\n<p>Saldr\u00e1 a la venta por un precio de 155 euros.<\/p>\n<p>Lo est\u00e1s viendo, los m\u00f3viles indios pisan fuerte con especificaciones propias de los tel\u00e9fonos de gama media a un precio muy competitivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primero llegaron los m\u00f3viles chinos pisando fuerte en el mercado espa\u00f1ol con marcas como Xioami, Huawei o Meizu. \u00a1Ahora es el turno de los m\u00f3viles indios! Las empresas de telefon\u00eda india est\u00e1n ganando relevancia y presencia poco a poco<\/p>\n","protected":false},"author":5,"featured_media":1618,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[6],"tags":[207],"class_list":["post-1614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-tendencias"],"uagb_featured_image_src":{"full":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg",800,495,false],"thumbnail":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios-150x150.jpg",150,150,true],"medium":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios-300x186.jpg",300,186,true],"medium_large":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios-768x475.jpg",768,475,true],"large":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg",800,495,false],"1536x1536":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg",800,495,false],"2048x2048":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg",800,495,false],"authorship-box-avatar":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg",150,93,false],"authorship-box-related":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg",70,43,false],"small":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg",300,186,false],"yarpp-thumbnail":["https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg",120,74,false]},"uagb_author_info":{"display_name":"Lowi","author_link":"https:\/\/www.lowi.es\/blog\/autor\/blog-lowi\/"},"uagb_comment_info":0,"uagb_excerpt":"Primero llegaron los m\u00f3viles chinos pisando fuerte en el mercado espa\u00f1ol con marcas como Xioami, Huawei o Meizu. \u00a1Ahora es el turno de los m\u00f3viles indios! Las empresas de telefon\u00eda india est\u00e1n ganando relevancia y presencia poco a poco","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.lowi.es\/blog\/wp-content\/uploads\/2016\/07\/mo\u0301viles-indios.jpg","_links":{"self":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/1614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/comments?post=1614"}],"version-history":[{"count":3,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/1614\/revisions"}],"predecessor-version":[{"id":2126,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/posts\/1614\/revisions\/2126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/media\/1618"}],"wp:attachment":[{"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/media?parent=1614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/categories?post=1614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lowi.es\/blog\/wp-json\/wp\/v2\/tags?post=1614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}